{"id":12024,"date":"2026-07-15T10:30:00","date_gmt":"2026-07-15T14:30:00","guid":{"rendered":"https:\/\/progresso.com.br\/?p=12024"},"modified":"2026-07-15T09:53:08","modified_gmt":"2026-07-15T13:53:08","slug":"acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/","title":{"rendered":"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Brasil, Argentina, Paraguai e Chile firmam memorandos para criar o C\u00e9u \u00danico Sul-americano, al\u00e9m de acordos bilaterais espec\u00edficos<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ag\u00eancia Gov | via Anac<br><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Ag\u00eancia Nacional de&nbsp;de Avia\u00e7\u00e3o Civil (Anac)&nbsp;assinou nesta ter\u00e7a-feira, 14 de julho, em Assun\u00e7\u00e3o, no Paraguai, um Memorando de Entendimentos&nbsp;(&nbsp;MoU&nbsp;)&nbsp;para Liberaliza\u00e7\u00e3o A\u00e9rea para o Desenvolvimento do C\u00e9u \u00danico Sul-americano&nbsp;(Acordo ALAS)&nbsp;. O&nbsp;documento&nbsp;foi assinado entre Brasil, Argentina, Paraguai e Chile e marca o in\u00edcio do processo para a integra\u00e7\u00e3o do modal a\u00e9reo na Am\u00e9rica do Sul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O&nbsp;MoU&nbsp;do acordo regional estabelece as bases para a constru\u00e7\u00e3o de um mercado integrado entre os&nbsp;quatro pa\u00edses, permitindo as negocia\u00e7\u00f5es para a gradual flexibiliza\u00e7\u00e3o e amplia\u00e7\u00e3o dos servi\u00e7os a\u00e9reos&nbsp;at\u00e9 a libera\u00e7\u00e3o plena das opera\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para a realiza\u00e7\u00e3o da tarefa, foi criado o Grupo de Trabalho Alas, integrado por representantes das autoridades de avia\u00e7\u00e3o dos pa\u00edses signat\u00e1rios&nbsp;e&nbsp;que dever\u00e1 apresentar, em at\u00e9 um ano a partir da assinatura do&nbsp;MoU&nbsp;, uma proposta&nbsp;para a implementa\u00e7\u00e3o progressiva do C\u00e9u \u00danico Sul-Americano&nbsp;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acordo prev\u00ea a implanta\u00e7\u00e3o progressiva e gradual dos passos para a integra\u00e7\u00e3o almejada, respeitando os processos e particularidades regulat\u00f3rias e jur\u00eddicas dos pa\u00edses signat\u00e1rios. Entre as propostas a serem estudadas&nbsp;est\u00e3o previstas medidas de harmoniza\u00e7\u00e3o regulat\u00f3ria, reconhecimento m\u00fatuo de certificados, licen\u00e7as e autoriza\u00e7\u00f5es, sustentabilidade ambiental, desenvolvimento de infraestrutura, capacita\u00e7\u00f5es e assist\u00eancias m\u00fatuas, entre outras.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Acordos&nbsp;bilaterais com&nbsp;Paraguai&nbsp;e Argentina<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m foram assinados dois acordos bilaterais, um&nbsp;com o Paraguai e o segundo com a Argentina. Estes&nbsp;MoUs&nbsp;incorporam a&nbsp;possibilidade de negocia\u00e7\u00e3o da&nbsp;s\u00e9tima liberdade do ar&nbsp;para opera\u00e7\u00f5es de passageiros&nbsp;(uma companhia a\u00e9rea pode operar voos comerciais&nbsp;entre dois pa\u00edses estrangeiros, sem que a rota tenha origem ou destino no seu pa\u00eds de registro. Isso significa que a empresa n\u00e3o precisa passar pelo seu territ\u00f3rio de origem para realizar o trajeto). Essa medida foi&nbsp;recentemente autorizada pela Portaria GM-MPOR n\u00ba 43&nbsp;, de 10 de julho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O acordo com o Paraguai&nbsp;tamb\u00e9m&nbsp;consolida&nbsp;a s\u00e9tima liberdade para&nbsp;opera\u00e7\u00f5es de&nbsp;cargas entre os dois pa\u00edses&nbsp;, que anteriormente estava prevista apenas no \u00e2mbito dos instrumentos negociados na Comiss\u00e3o Latino-Americana de Avia\u00e7\u00e3o Civil (CLAC)&nbsp;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta assinatura tamb\u00e9m est\u00e1 relacionada ao avan\u00e7o dos entendimentos para a cria\u00e7\u00e3o de um&nbsp;espa\u00e7o a\u00e9reo integrado na Am\u00e9rica do Sul, representando ainda mais um passo para a coopera\u00e7\u00e3o do Brasil com os pa\u00edses vizinhos, ampliando a conectividade do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Por Anac<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Brasil, Argentina, Paraguai e Chile firmam memorandos para criar o C\u00e9u \u00danico Sul-americano, al\u00e9m de acordos bilaterais espec\u00edficos Ag\u00eancia Gov | via Anac A Ag\u00eancia Nacional de&nbsp;de Avia\u00e7\u00e3o Civil (Anac)&nbsp;assinou nesta ter\u00e7a-feira, 14 de julho, em Assun\u00e7\u00e3o, no Paraguai, um Memorando de Entendimentos&nbsp;(&nbsp;MoU&nbsp;)&nbsp;para Liberaliza\u00e7\u00e3o A\u00e9rea para o Desenvolvimento do C\u00e9u \u00danico Sul-americano&nbsp;(Acordo ALAS)&nbsp;. O&nbsp;documento&nbsp;foi assinado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,7],"tags":[],"class_list":["post-12024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Brasil, Argentina, Paraguai e Chile firmam memorandos para criar o C\u00e9u \u00danico Sul-americano, al\u00e9m de acordos bilaterais espec\u00edficos Ag\u00eancia Gov | via Anac A Ag\u00eancia Nacional de&nbsp;de Avia\u00e7\u00e3o Civil (Anac)&nbsp;assinou nesta ter\u00e7a-feira, 14 de julho, em Assun\u00e7\u00e3o, no Paraguai, um Memorando de Entendimentos&nbsp;(&nbsp;MoU&nbsp;)&nbsp;para Liberaliza\u00e7\u00e3o A\u00e9rea para o Desenvolvimento do C\u00e9u \u00danico Sul-americano&nbsp;(Acordo ALAS)&nbsp;. O&nbsp;documento&nbsp;foi assinado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T14:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"815\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\"},\"author\":{\"name\":\"Rose\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\"},\"headline\":\"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos\",\"datePublished\":\"2026-07-15T14:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\"},\"wordCount\":512,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg\",\"articleSection\":[\"Em destaque\",\"Internacional\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\",\"name\":\"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg\",\"datePublished\":\"2026-07-15T14:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg\",\"width\":815,\"height\":507,\"caption\":\"(Foto: Arquivo)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\",\"name\":\"Rose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"caption\":\"Rose\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/rose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/","og_locale":"pt_BR","og_type":"article","og_title":"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos - O PROGRESSO","og_description":"Brasil, Argentina, Paraguai e Chile firmam memorandos para criar o C\u00e9u \u00danico Sul-americano, al\u00e9m de acordos bilaterais espec\u00edficos Ag\u00eancia Gov | via Anac A Ag\u00eancia Nacional de&nbsp;de Avia\u00e7\u00e3o Civil (Anac)&nbsp;assinou nesta ter\u00e7a-feira, 14 de julho, em Assun\u00e7\u00e3o, no Paraguai, um Memorando de Entendimentos&nbsp;(&nbsp;MoU&nbsp;)&nbsp;para Liberaliza\u00e7\u00e3o A\u00e9rea para o Desenvolvimento do C\u00e9u \u00danico Sul-americano&nbsp;(Acordo ALAS)&nbsp;. O&nbsp;documento&nbsp;foi assinado [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-07-15T14:30:00+00:00","og_image":[{"width":815,"height":507,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg","type":"image\/jpeg"}],"author":"Rose","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rose","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/"},"author":{"name":"Rose","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b"},"headline":"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos","datePublished":"2026-07-15T14:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/"},"wordCount":512,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg","articleSection":["Em destaque","Internacional"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/","name":"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg","datePublished":"2026-07-15T14:30:00+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/aviacao.jpg","width":815,"height":507,"caption":"(Foto: Arquivo)"},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/acordos-regionais-vao-integrar-o-transporte-aereo-entre-paises-sul-americanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"Acordos regionais v\u00e3o integrar o transporte a\u00e9reo entre pa\u00edses sul-americanos"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b","name":"Rose","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","caption":"Rose"},"url":"https:\/\/progresso.com.br\/index.php\/author\/rose\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12024"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12024\/revisions"}],"predecessor-version":[{"id":12026,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12024\/revisions\/12026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/12025"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}