{"id":12027,"date":"2026-07-15T11:00:00","date_gmt":"2026-07-15T15:00:00","guid":{"rendered":"https:\/\/progresso.com.br\/?p=12027"},"modified":"2026-07-15T10:43:04","modified_gmt":"2026-07-15T14:43:04","slug":"setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/","title":{"rendered":"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Em 12 meses, alta acumulada \u00e9 de 2,6%, segundo levantamento do IBGE<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Bruno de Freitas Moura &#8211;  Ag\u00eancia Brasil <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O setor de servi\u00e7os, que re\u00fane atividades como turismo, restaurantes, sal\u00e3o de beleza, internet e tecnologia da informa\u00e7\u00e3o (TI), recuou 0,4% em maio, puxado pelo desempenho negativo dos transportes.<\/strong><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1696732&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1696732&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo a Secretaria da Pol\u00edtica Econ\u00f4mica (SPE) do Minist\u00e9rio da Fazenda, o resultado veio abaixo das expectativas de mercado (intervalo de -0,3% a 0,6%; mediana de 0,0%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na compara\u00e7\u00e3o com o mesmo m\u00eas do ano passado, o setor cresceu 0,4%. De janeiro a maio, avan\u00e7ou 1,9% em rela\u00e7\u00e3o ao mesmo per\u00edodo de 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No acumulado de 12 meses, a alta acumulada \u00e9 de 2,6%. Esse n\u00famero representa redu\u00e7\u00e3o no ritmo de expans\u00e3o, uma vez que em abril estava em 2,9%.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os dados fazem parte da&nbsp;<a href=\"https:\/\/agenciadenoticias.ibge.gov.br\/media\/com_mediaibge\/arquivos\/f70b035b9c9026bd915d5399466ca2f6.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Pesquisa Mensal de Servi\u00e7os<\/a>, divulgada nesta quarta-feira (15) pelo Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com os resultados de maio, o setor fica 19,6% acima do n\u00edvel pr\u00e9-pandemia de covid-19 (fevereiro de 2020) e 0,5% abaixo do maior n\u00edvel j\u00e1 registrado, que pertence a outubro de 2025. A pesquisa traz dados desde janeiro de 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veja o comportamento do setor nos \u00faltimos meses, comparado ao m\u00eas imediatamente anterior:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Maio: -0,4%<\/li>\n\n\n\n<li>Abril: 1,1%<\/li>\n\n\n\n<li>Mar\u00e7o: -0,9%<\/li>\n\n\n\n<li>Fevereiro: 0,1%<\/li>\n\n\n\n<li>Janeiro: 0%<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Freio nos transportes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O IBGE aponta que dos cinco grupos de atividades pesquisadas, dois apresentaram queda na passagem de abril para maio.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Servi\u00e7os prestados \u00e0s fam\u00edlias: 0,2%<\/li>\n\n\n\n<li>Servi\u00e7os de informa\u00e7\u00e3o e comunica\u00e7\u00e3o: 0%<\/li>\n\n\n\n<li>Servi\u00e7os profissionais, administrativos e complementares: 2%<\/li>\n\n\n\n<li>Transportes, servi\u00e7os auxiliares aos transportes e correio: -1%<\/li>\n\n\n\n<li>Outros servi\u00e7os: -1,9%<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A queda dos transportes foi o que mais puxou o setor de servi\u00e7os para baixo em maio porque o item tem peso de um ter\u00e7o (33,67%) na pesquisa.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o analista da pesquisa, Rodrigo Lobo, houve \u201cmenor receita das empresas de transporte a\u00e9reo de passageiros, transporte rodovi\u00e1rio de carga e de log\u00edstica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Em maio de 2026, o volume de transporte de passageiros recuou 1,3% na compara\u00e7\u00e3o com o m\u00eas imediatamente anterior.<\/strong>&nbsp;J\u00e1 o volume do transporte de cargas teve varia\u00e7\u00e3o negativa de 0,2%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lobo destaca tamb\u00e9m que os servi\u00e7os \u00e0s fam\u00edlias alcan\u00e7aram o maior patamar desde dezembro de 2014. Para ele, \u00e9 uma resposta a vari\u00e1veis econ\u00f4micas \u201ccomo desemprego baixo, massa de rendimentos elevadas e n\u00edvel de pre\u00e7os controlado\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00cdndice de atividades tur\u00edsticas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A Pesquisa Mensal de Servi\u00e7os traz ainda o \u00edndice de atividades tur\u00edsticas (Iatur), que recuou 0,4% em maio, na compara\u00e7\u00e3o com o m\u00eas anterior<\/strong>. J\u00e1 em compara\u00e7\u00e3o com o acumulado de 12 meses, h\u00e1 expans\u00e3o de 1,7%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esses resultados deixam as atividades de turismo 10,8% acima do patamar pr\u00e9-pandemia de covid-19 e 2,5% abaixo do maior n\u00edvel j\u00e1 alcan\u00e7ado, em dezembro de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>O Iatur re\u00fane 22 das 166 atividades de servi\u00e7os investigadas na pesquisa e que s\u00e3o ligadas \u00e0 atividade tur\u00edstica, como hot\u00e9is, ag\u00eancias de viagens, buf\u00ea e transporte a\u00e9reo de passageiros.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o divulgadas informa\u00e7\u00f5es de 17 unidades da federa\u00e7\u00e3o: Cear\u00e1, Pernambuco, Bahia, Minas Gerais, Esp\u00edrito Santo, Rio de Janeiro, S\u00e3o Paulo, Paran\u00e1, Santa Catarina, Rio Grande do Sul, Goi\u00e1s e Distrito Federal, Amazonas, Par\u00e1, Mato Grosso, Alagoas e Rio Grande do Norte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 12 meses, alta acumulada \u00e9 de 2,6%, segundo levantamento do IBGE Bruno de Freitas Moura &#8211; Ag\u00eancia Brasil O setor de servi\u00e7os, que re\u00fane atividades como turismo, restaurantes, sal\u00e3o de beleza, internet e tecnologia da informa\u00e7\u00e3o (TI), recuou 0,4% em maio, puxado pelo desempenho negativo dos transportes. Segundo a Secretaria da Pol\u00edtica Econ\u00f4mica (SPE) [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,2],"tags":[],"class_list":["post-12027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Em 12 meses, alta acumulada \u00e9 de 2,6%, segundo levantamento do IBGE Bruno de Freitas Moura &#8211; Ag\u00eancia Brasil O setor de servi\u00e7os, que re\u00fane atividades como turismo, restaurantes, sal\u00e3o de beleza, internet e tecnologia da informa\u00e7\u00e3o (TI), recuou 0,4% em maio, puxado pelo desempenho negativo dos transportes. Segundo a Secretaria da Pol\u00edtica Econ\u00f4mica (SPE) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T15:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\"},\"author\":{\"name\":\"Rose\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\"},\"headline\":\"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes\",\"datePublished\":\"2026-07-15T15:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\"},\"wordCount\":565,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp\",\"articleSection\":[\"Brasil\",\"Em destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\",\"name\":\"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp\",\"datePublished\":\"2026-07-15T15:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp\",\"width\":1170,\"height\":700,\"caption\":\"(Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\",\"name\":\"Rose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"caption\":\"Rose\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/rose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/","og_locale":"pt_BR","og_type":"article","og_title":"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes - O PROGRESSO","og_description":"Em 12 meses, alta acumulada \u00e9 de 2,6%, segundo levantamento do IBGE Bruno de Freitas Moura &#8211; Ag\u00eancia Brasil O setor de servi\u00e7os, que re\u00fane atividades como turismo, restaurantes, sal\u00e3o de beleza, internet e tecnologia da informa\u00e7\u00e3o (TI), recuou 0,4% em maio, puxado pelo desempenho negativo dos transportes. Segundo a Secretaria da Pol\u00edtica Econ\u00f4mica (SPE) [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-07-15T15:00:00+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp","type":"image\/webp"}],"author":"Rose","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rose","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/"},"author":{"name":"Rose","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b"},"headline":"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes","datePublished":"2026-07-15T15:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/"},"wordCount":565,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp","articleSection":["Brasil","Em destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/","name":"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp","datePublished":"2026-07-15T15:00:00+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/mg_2404.webp","width":1170,"height":700,"caption":"(Foto: Fernando Fraz\u00e3o\/Ag\u00eancia Brasil)"},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/setor-de-servicos-cai-04-em-maio-por-recuo-na-area-de-transportes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"Setor de servi\u00e7os cai 0,4% em maio por recuo na \u00e1rea de transportes"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b","name":"Rose","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","caption":"Rose"},"url":"https:\/\/progresso.com.br\/index.php\/author\/rose\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12027"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12027\/revisions"}],"predecessor-version":[{"id":12029,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12027\/revisions\/12029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/12028"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}