{"id":12039,"date":"2026-07-15T13:00:00","date_gmt":"2026-07-15T17:00:00","guid":{"rendered":"https:\/\/progresso.com.br\/?p=12039"},"modified":"2026-07-15T12:24:50","modified_gmt":"2026-07-15T16:24:50","slug":"dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/","title":{"rendered":"Dino intima partidos a explicar controle de emendas parlamentares"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Decis\u00e3o foi motivada por declara\u00e7\u00f5es de presidente do PL<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Alex Rodrigues &#8211;  Ag\u00eancia Brasil<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ministro Fl\u00e1vio Dino, do Supremo Tribunal Federal (STF),&nbsp;<strong>determinou que os presidentes de todos os partidos com representa\u00e7\u00e3o no Congresso Nacional expliquem, em at\u00e9 dez dias \u00fateis, se interferem na destina\u00e7\u00e3o de emendas parlamentares<\/strong>.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1696741&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1696741&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Proferida nesta quarta-feira (15), a intima\u00e7\u00e3o foi motivada por uma entrevista que o presidente do Partido Liberal (PL), Valdemar Costa Neto, concedeu na ter\u00e7a-feira (14), \u00e0&nbsp;<em>GloboNews<\/em>, e na qual confirmou que os dirigentes partid\u00e1rios interferem na indica\u00e7\u00e3o de emendas parlamentares.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cValdemar Costa Neto \u00e9 um pol\u00edtico de destaque e preside um dos maiores partidos brasileiros, logo, suas afirma\u00e7\u00f5es p\u00fablicas merecem aten\u00e7\u00e3o\u201d, escreveu Dino em seu despacho.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">O ministro Fl\u00e1vio Dino \u00e9 o relator da&nbsp;<a href=\"https:\/\/noticias-stf-wp-prd.s3.sa-east-1.amazonaws.com\/wp-content\/uploads\/wpallimport\/uploads\/2024\/12\/29145208\/ADPF-854-29122024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Argui\u00e7\u00e3o de Descumprimento de Preceito Fundamental (ADPF) n\u00ba 854<\/a>,&nbsp;<strong>instaurada para apurar a constitucionalidade e eventuais irregularidades na execu\u00e7\u00e3o de emendas parlamentares<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em seu mais recente despacho, Dino destaca que Costa Neto concedeu a entrevista no mesmo dia em que ele determinou que o Congresso Nacional explique, entre outras a\u00e7\u00f5es, se pol\u00edticos sem mandato interferem no processo de escolha dos destinat\u00e1rios das emendas parlamentares, pr\u00e1tica que o ministro j\u00e1 tinha afirmado que viola os princ\u00edpios da moralidade, legalidade e finalidade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEm decis\u00e3o de [ter\u00e7a-feira] 14 de julho de 2026, ressaltei que a proposi\u00e7\u00e3o e a delibera\u00e7\u00e3o sobre emendas parlamentares constituem prerrogativas inerentes ao exerc\u00edcio do mandato parlamentar, competindo exclusivamente aos membros do Poder Legislativo no curso de seus mandatos\u201d, escreveu Dino na decis\u00e3o desta quarta-feira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cN\u00e3o obstante, fatos p\u00fablicos e not\u00f3rios, consubstanciados em manifesta\u00e7\u00f5es aparentemente contr\u00e1rias a essa premissa, suscitam, ao menos em tese, d\u00favidas quanto \u00e0 sua estrita observ\u00e2ncia, circunst\u00e2ncia que recomenda a obten\u00e7\u00e3o de esclarecimentos, visando ao fiel cumprimento das decis\u00f5es do Plen\u00e1rio do STF\u201d, acrescenta o ministro, referindo-se \u00e0 entrevista de Costa Neto ao programa&nbsp;<em>Est\u00fadio i<\/em>, da&nbsp;<em>GloboNews<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cIndagado se dirigentes partid\u00e1rios interferem na destina\u00e7\u00e3o de emendas parlamentares, [Costa Neto] respondeu afirmativamente. Na ocasi\u00e3o, afirmou, ainda, que outros presidentes de partidos tamb\u00e9m indicam emendas parlamentares\u201d, destacou Dino.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O ministro argumenta ainda que, caso as informa\u00e7\u00f5es do presidente do PL sejam procedentes, \u201cconstituem uma novidade relevante\u201d, j\u00e1 que a apura\u00e7\u00e3o em curso, no STF, desde 2021, \u201cn\u00e3o cont\u00e9m registro dessa modalidade de emendas ao Or\u00e7amento Geral da Uni\u00e3o\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Al\u00e9m do PL, de Costa Neto, a decis\u00e3o de Dino se aplica a outras 20 legendas: Avante, Cidadania, MDB, Miss\u00e3o, Novo, PCdoB, PDT, Podemos, PP, PRD, PSB, PSD, PSDB, PSOL, PT, PV, REDE, Republicanos, Solidariedade e Uni\u00e3o Brasil.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada partido dever\u00e1 esclarecer se seu presidente disp\u00f5e de cotas, reservas ou qualquer outro mecanismo de aloca\u00e7\u00e3o de emendas parlamentares e, em caso positivo, sua natureza, finalidade e abrang\u00eancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m dever\u00e3o esclarecer a quem compete autorizar e deliberar sobre a utiliza\u00e7\u00e3o da cota ou mecanismo; o fundamento jur\u00eddico-normativo que embasa tal pr\u00e1tica; o instrumento por meio do qual tais mecanismos s\u00e3o formalizados (normas, atas ou similares) e como \u00e9 definida a destina\u00e7\u00e3o dos respectivos recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs informa\u00e7\u00f5es ora requisitadas s\u00e3o relevantes para subsidiar a defini\u00e7\u00e3o de provid\u00eancias eventualmente necess\u00e1rias ao aperfei\u00e7oamento dos mecanismos de transpar\u00eancia e rastreabilidade das emendas parlamentares, a fim de garantir o cumprimento das decis\u00f5es do Plen\u00e1rio do STF\u201d, justificou Dino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Na sexta-feira (10), o ministro&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-07\/dino-bloqueia-r-119-milhoes-de-valdemar-por-suspeitas-em-emendas\" target=\"_blank\" rel=\"noreferrer noopener\">determinou o bloqueio de R$ 119 milh\u00f5es<\/a>&nbsp;em bens atribu\u00eddos a Costa Neto<\/strong>&nbsp;e de&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2026-07\/stf-bloqueia-r-6-mi-de-eduardo-cunha-por-indicacao-de-emendas\" target=\"_blank\" rel=\"noreferrer noopener\">R$ 6 milh\u00f5es do ex-deputado federal e ex-presidente da C\u00e2mara Eduardo Cunha<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na ocasi\u00e3o, a defesa do presidente do PL argumentou que as medidas cautelares foram decretadas com base em \u201cpremissas fr\u00e1geis, infer\u00eancias subjetivas e uma indevida criminaliza\u00e7\u00e3o da atividade pol\u00edtico-partid\u00e1ria\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A defesa de Costa Neto informou que ele nega a pr\u00e1tica de qualquer crime<\/strong>&nbsp;e considera \u201cnatural e leg\u00edtimo, no sistema democr\u00e1tico, que um presidente partid\u00e1rio dialogue com parlamentares, defenda prioridades program\u00e1ticas, articule interesses nacionais e regionais e influencie politicamente sua bancada\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decis\u00e3o foi motivada por declara\u00e7\u00f5es de presidente do PL Alex Rodrigues &#8211; Ag\u00eancia Brasil O ministro Fl\u00e1vio Dino, do Supremo Tribunal Federal (STF),&nbsp;determinou que os presidentes de todos os partidos com representa\u00e7\u00e3o no Congresso Nacional expliquem, em at\u00e9 dez dias \u00fateis, se interferem na destina\u00e7\u00e3o de emendas parlamentares. Proferida nesta quarta-feira (15), a intima\u00e7\u00e3o foi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,9],"tags":[],"class_list":["post-12039","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dino intima partidos a explicar controle de emendas parlamentares - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dino intima partidos a explicar controle de emendas parlamentares - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Decis\u00e3o foi motivada por declara\u00e7\u00f5es de presidente do PL Alex Rodrigues &#8211; Ag\u00eancia Brasil O ministro Fl\u00e1vio Dino, do Supremo Tribunal Federal (STF),&nbsp;determinou que os presidentes de todos os partidos com representa\u00e7\u00e3o no Congresso Nacional expliquem, em at\u00e9 dez dias \u00fateis, se interferem na destina\u00e7\u00e3o de emendas parlamentares. Proferida nesta quarta-feira (15), a intima\u00e7\u00e3o foi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T17:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Rose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\"},\"author\":{\"name\":\"Rose\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\"},\"headline\":\"Dino intima partidos a explicar controle de emendas parlamentares\",\"datePublished\":\"2026-07-15T17:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\"},\"wordCount\":723,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp\",\"articleSection\":[\"Em destaque\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\",\"name\":\"Dino intima partidos a explicar controle de emendas parlamentares - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp\",\"datePublished\":\"2026-07-15T17:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp\",\"width\":1170,\"height\":700,\"caption\":\"(Foto:Pablo Valadares\/C\u00e2mara dos Deputados)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dino intima partidos a explicar controle de emendas parlamentares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\",\"name\":\"Rose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"caption\":\"Rose\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/rose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dino intima partidos a explicar controle de emendas parlamentares - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/","og_locale":"pt_BR","og_type":"article","og_title":"Dino intima partidos a explicar controle de emendas parlamentares - O PROGRESSO","og_description":"Decis\u00e3o foi motivada por declara\u00e7\u00f5es de presidente do PL Alex Rodrigues &#8211; Ag\u00eancia Brasil O ministro Fl\u00e1vio Dino, do Supremo Tribunal Federal (STF),&nbsp;determinou que os presidentes de todos os partidos com representa\u00e7\u00e3o no Congresso Nacional expliquem, em at\u00e9 dez dias \u00fateis, se interferem na destina\u00e7\u00e3o de emendas parlamentares. Proferida nesta quarta-feira (15), a intima\u00e7\u00e3o foi [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-07-15T17:00:00+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp","type":"image\/webp"}],"author":"Rose","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rose","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/"},"author":{"name":"Rose","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b"},"headline":"Dino intima partidos a explicar controle de emendas parlamentares","datePublished":"2026-07-15T17:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/"},"wordCount":723,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp","articleSection":["Em destaque","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/","name":"Dino intima partidos a explicar controle de emendas parlamentares - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp","datePublished":"2026-07-15T17:00:00+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/07\/img20210309121349708.webp","width":1170,"height":700,"caption":"(Foto:Pablo Valadares\/C\u00e2mara dos Deputados)"},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/07\/15\/dino-intima-partidos-a-explicar-controle-de-emendas-parlamentares\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"Dino intima partidos a explicar controle de emendas parlamentares"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b","name":"Rose","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","caption":"Rose"},"url":"https:\/\/progresso.com.br\/index.php\/author\/rose\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12039"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12039\/revisions"}],"predecessor-version":[{"id":12041,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12039\/revisions\/12041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/12040"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}