{"id":5732,"date":"2026-05-07T15:00:37","date_gmt":"2026-05-07T19:00:37","guid":{"rendered":"https:\/\/progresso.com.br\/?p=5732"},"modified":"2026-05-07T15:00:37","modified_gmt":"2026-05-07T19:00:37","slug":"corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/","title":{"rendered":"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina"},"content":{"rendered":"\n<p><em>Lucas Pordeus Le\u00f3n, da Ag\u00eancia Brasil<\/em><\/p>\n\n\n\n<p>O governo do ultraliberal Javier Milei enfrenta o pior momento \u00e0 frente da Argentina em meio a esc\u00e2ndalos de corrup\u00e7\u00e3o, queda nos \u00edndices de popularidade e na atividade econ\u00f4mica e industrial.&nbsp;<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1688574&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1688574&amp;o=node\"><\/p>\n\n\n\n<p><strong>A infla\u00e7\u00e3o, at\u00e9 ent\u00e3o principal vitrine pol\u00edtica da Casa Rosada, voltou a acelerar.<\/strong>&nbsp;Ap\u00f3s reduzir a infla\u00e7\u00e3o mensal de dois d\u00edgitos, no final de 2023, para cerca de 2% ao m\u00eas, ao longo de 2025, os \u00edndices de pre\u00e7os voltaram a subir entre o final do ano passado e o in\u00edcio de 2026, chegando a 3,4% em mar\u00e7o deste ano.<\/p>\n\n\n\n<p>A acelera\u00e7\u00e3o recente fez Milei reconhecer dificuldades econ\u00f4micas publicamente.&nbsp;<strong>\u201cO dado \u00e9 ruim\u201d, disse em uma rede social.<\/strong><\/p>\n\n\n\n<p>Ao mesmo tempo, a atividade econ\u00f4mica na Argentina apresentou uma retra\u00e7\u00e3o de 2,6% em fevereiro, se comparado a janeiro, com uma queda acumulada de 2,1% nos \u00faltimos 12 meses.<\/p>\n\n\n\n<p><strong>Talvez a situa\u00e7\u00e3o mais preocupante seja a queda na produ\u00e7\u00e3o industrial<\/strong>, que registrou baixa de 4% em fevereiro, acumulando uma queda de 8,7% nos \u00faltimos 12 meses.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plano econ\u00f4mico<\/h2>\n\n\n\n<p>O professor de economia da Funda\u00e7\u00e3o Getulio Vargas de S\u00e3o Paulo (FGV-SP) Paulo Gala comentou que o plano econ\u00f4mico de Milei \u00e9 \u201csimplista\u201d e n\u00e3o tem dado conta de reverter completamente \u00e0 situa\u00e7\u00e3o econ\u00f4mica que herdou.<\/p>\n\n\n\n<p><strong><em>\u201cAs pessoas n\u00e3o confiam mais no peso [moeda argentina]. Elas dolarizam [cotam em d\u00f3lar] os contratos, um pouco parecido com o que aconteceu com o Brasil antes do Plano Real. Com isso, com qualquer coisa a infla\u00e7\u00e3o volta a acelerar. Reduzir o tamanho do Estado n\u00e3o resolve nada\u201d, disse.<\/em><\/strong><\/p>\n\n\n\n<p>O governo de Milei prega a redu\u00e7\u00e3o do tamanho do Estado, com corte de gastos e austeridade fiscal, como medidas para conter a infla\u00e7\u00e3o e recuperar a economia.<\/p>\n\n\n\n<p>O economista Gala avalia que o plano de Milei n\u00e3o deve ir muito longe, argumentando que seriam necess\u00e1rias outras medidas, como instituir uma nova moeda.&nbsp;<\/p>\n\n\n\n<p><strong>Ele destacou ainda que o peso argentino est\u00e1 sobrevalorizado, o que tem, segundo ele, destru\u00eddo a ind\u00fastria do pa\u00eds.<\/strong><\/p>\n\n\n\n<p>\u201cEsse mergulho da atividade manufatureira \u00e9 fatal para o pa\u00eds porque esse setor \u00e9 respons\u00e1vel por aumento de produtividade, por ganhos tecnol\u00f3gicos. Esse dado da ind\u00fastria \u00e9 muito ruim. Essa abertura comercial violenta que o Milei tem feito tamb\u00e9m destr\u00f3i o pouco que restou de ind\u00fastria na Argentina\u201d, completou.<\/p>\n\n\n\n<p>Para o especialista, a tend\u00eancia \u00e9 a Argentina se desindustrializar cada vez mais, focando a economia apenas no setor agroexportador de mat\u00e9rias-primas.&nbsp;<\/p>\n\n\n\n<p><strong>\u201cN\u00e3o est\u00e1 descartado um cen\u00e1rio de recess\u00e3o e, possivelmente, nova crise cambial com enorme d\u00edvida em d\u00f3lares\u201d, analisa Paulo Gala.<\/strong><\/p>\n\n\n\n<p>A Argentina tem contra\u00eddo novos empr\u00e9stimos com bancos internacionais, em d\u00f3lares, para segurar o valor do peso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Popularidade<\/h2>\n\n\n\n<p><strong>Al\u00e9m da situa\u00e7\u00e3o econ\u00f4mica dif\u00edcil, recentes casos de corrup\u00e7\u00e3o t\u00eam contribu\u00eddo para a queda nos \u00edndices de popularidade do governo.<\/strong><\/p>\n\n\n\n<p>Um dos exemplos \u00e9 a investiga\u00e7\u00e3o sobre suposto enriquecimento il\u00edcito do chefe de gabinete de Milei, Manuel Adorni, que tem tido que se explicar sobre viagens de luxo e compra e reforma de im\u00f3veis supostamente incompat\u00edveis com sua renda.<\/p>\n\n\n\n<p>As pesquisas de opini\u00e3o t\u00eam registrado \u00edndices de desaprova\u00e7\u00e3o superiores a 60%, marcando os piores n\u00fameros desde que assumiu a Casa Rosada, em dezembro de 2023.&nbsp;<\/p>\n\n\n\n<p>A da Atlas Intel do final de abril indicou uma reprova\u00e7\u00e3o de 63% da figura do Milei, com uma aprova\u00e7\u00e3o de 35%.<\/p>\n\n\n\n<p><strong>A corrup\u00e7\u00e3o e o desempenho econ\u00f4mico s\u00e3o os fatores determinantes para a queda na popularidade.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Segundo a&nbsp;<a href=\"https:\/\/zentrixdata.com.ar\/tiembla-el-relato-libertario-67-cree-que-se-rompio-el-pacto-anticasta-y-cae-la-aprobacion-de-gestion-de-milei\/\" target=\"_blank\" rel=\"noreferrer noopener\">consultoria Zentrix<\/a>, 66,6% da popula\u00e7\u00e3o avaliam que se \u201cquebrou\u201d a promessa \u201canti-casta\u201d de combate \u00e0 corrup\u00e7\u00e3o de Milei.&nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lucas Pordeus Le\u00f3n, da Ag\u00eancia Brasil O governo do ultraliberal Javier Milei enfrenta o pior momento \u00e0 frente da Argentina em meio a esc\u00e2ndalos de corrup\u00e7\u00e3o, queda nos \u00edndices de popularidade e na atividade econ\u00f4mica e industrial.&nbsp; A infla\u00e7\u00e3o, at\u00e9 ent\u00e3o principal vitrine pol\u00edtica da Casa Rosada, voltou a acelerar.&nbsp;Ap\u00f3s reduzir a infla\u00e7\u00e3o mensal de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-5732","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Lucas Pordeus Le\u00f3n, da Ag\u00eancia Brasil O governo do ultraliberal Javier Milei enfrenta o pior momento \u00e0 frente da Argentina em meio a esc\u00e2ndalos de corrup\u00e7\u00e3o, queda nos \u00edndices de popularidade e na atividade econ\u00f4mica e industrial.&nbsp; A infla\u00e7\u00e3o, at\u00e9 ent\u00e3o principal vitrine pol\u00edtica da Casa Rosada, voltou a acelerar.&nbsp;Ap\u00f3s reduzir a infla\u00e7\u00e3o mensal de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T19:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Alfredo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alfredo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\"},\"author\":{\"name\":\"Alfredo\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2\"},\"headline\":\"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina\",\"datePublished\":\"2026-05-07T19:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp\",\"articleSection\":[\"Internacional\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\",\"name\":\"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp\",\"datePublished\":\"2026-05-07T19:00:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp\",\"width\":800,\"height\":533,\"caption\":\"Governo enfrenta queda de popularidade e acumula casos de corrup\u00e7\u00e3o.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2\",\"name\":\"Alfredo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g\",\"caption\":\"Alfredo\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/alfredo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/","og_locale":"pt_BR","og_type":"article","og_title":"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina - O PROGRESSO","og_description":"Lucas Pordeus Le\u00f3n, da Ag\u00eancia Brasil O governo do ultraliberal Javier Milei enfrenta o pior momento \u00e0 frente da Argentina em meio a esc\u00e2ndalos de corrup\u00e7\u00e3o, queda nos \u00edndices de popularidade e na atividade econ\u00f4mica e industrial.&nbsp; A infla\u00e7\u00e3o, at\u00e9 ent\u00e3o principal vitrine pol\u00edtica da Casa Rosada, voltou a acelerar.&nbsp;Ap\u00f3s reduzir a infla\u00e7\u00e3o mensal de [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-05-07T19:00:37+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp","type":"image\/webp"}],"author":"Alfredo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alfredo","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/"},"author":{"name":"Alfredo","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2"},"headline":"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina","datePublished":"2026-05-07T19:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp","articleSection":["Internacional"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/","name":"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp","datePublished":"2026-05-07T19:00:37+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/protesto-na-argentina.webp","width":800,"height":533,"caption":"Governo enfrenta queda de popularidade e acumula casos de corrup\u00e7\u00e3o."},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/corrupcao-inflacao-e-economia-em-queda-desafiam-milei-na-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"Corrup\u00e7\u00e3o, infla\u00e7\u00e3o e economia em queda desafiam Milei na Argentina"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2","name":"Alfredo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g","caption":"Alfredo"},"url":"https:\/\/progresso.com.br\/index.php\/author\/alfredo\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5732"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5732\/revisions"}],"predecessor-version":[{"id":5734,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5732\/revisions\/5734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/5733"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}