{"id":5761,"date":"2026-05-07T17:30:00","date_gmt":"2026-05-07T21:30:00","guid":{"rendered":"https:\/\/progresso.com.br\/?p=5761"},"modified":"2026-05-07T17:04:50","modified_gmt":"2026-05-07T21:04:50","slug":"ms-debate-tecnologia-digital-para-modernizar-servicos-publicos","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/","title":{"rendered":"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos"},"content":{"rendered":"\n<p><em>Comunica\u00e7\u00e3o do Governo de MS<\/em><\/p>\n\n\n\n<p>Com foco no uso da tecnologia digital para o servi\u00e7o p\u00fablico, o governador Eduardo Riedel participou nesta quinta-feira (7) de uma reuni\u00e3o com a Meta, em S\u00e3o Paulo. O objetivo \u00e9 avaliar grandes oportunidades para tornar a gest\u00e3o estadual e o atendimento ao cidad\u00e3o mais \u00e1gil e eficiente.<\/p>\n\n\n\n<p>Neste encontro foram apresentadas ao governador solu\u00e7\u00f5es tecnol\u00f3gicas para o fortalecimento da comunica\u00e7\u00e3o institucional e presta\u00e7\u00e3o de servi\u00e7os p\u00fablicos, utilizando ferramentas como IA (Intelig\u00eancia Artificial), chatbots e outras alternativas.<\/p>\n\n\n\n<p>\u201cEstamos aqui em uma visita na Meta em S\u00e3o Paulo. Foi uma reuni\u00e3o muito produtiva. Pode acrescentar neste processo que estamos de transforma\u00e7\u00e3o digital em Mato Grosso do Sul. Estas empresas como podem contribuir muito. Sa\u00edmos aqui com grandes oportunidades de melhorias de processo interno, de relacionamento com os cidad\u00e3os\u201d, destacou o governador.<\/p>\n\n\n\n<p>A Meta \u00e9 um conglomerado de tecnologia e m\u00eddia social, com sede na Calif\u00f3rnia, nos Estados Unidos. Ela \u00e9 considerada uma das empresas mais valiosas do mundo, estando entre as cinco grandes do setor de tecnologia. Oferece plataformas de rede social como Facebook, Instagram e WhatsApp, al\u00e9m de um pacote de outros produtos.<\/p>\n\n\n\n<p><strong>Prioridade<\/strong><\/p>\n\n\n\n<p>Riedel lembrou que Mato Grosso do Sul est\u00e1 caminhando r\u00e1pido para tornar o servi\u00e7o p\u00fablico estadual mais \u00e1gil, eficiente, gerando facilidades para a popula\u00e7\u00e3o. \u201cUma base de infraestrutura e tecnologia est\u00e1 sendo realizada, agora vamos partir para que os servi\u00e7os oferecidos sejam mais \u00e1geis, intensos, menos burocr\u00e1ticos, principalmente nas a\u00e7\u00f5es de pol\u00edtica p\u00fablica\u201d.<\/p>\n\n\n\n<p>Construir um Estado cada vez mais digital \u00e9 uma das prioridades da atual gest\u00e3o. Al\u00e9m de seguir as inova\u00e7\u00f5es tecnol\u00f3gicas, o desafio \u00e9 promover parcerias que possam refletir diretamente na vida do cidad\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image\" id=\"attachment_540826\"><a href=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-07-scaled.jpeg\"><img decoding=\"async\" src=\"https:\/\/agenciadenoticias.ms.gov.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-07-1024x768.jpeg\" alt=\"\" class=\"wp-image-540826\"\/><\/a><figcaption class=\"wp-element-caption\">Reuni\u00e3o do Governo do Estado com representantes da Meta em S\u00e3o Paulo<\/figcaption><\/figure>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comunica\u00e7\u00e3o do Governo de MS Com foco no uso da tecnologia digital para o servi\u00e7o p\u00fablico, o governador Eduardo Riedel participou nesta quinta-feira (7) de uma reuni\u00e3o com a Meta, em S\u00e3o Paulo. O objetivo \u00e9 avaliar grandes oportunidades para tornar a gest\u00e3o estadual e o atendimento ao cidad\u00e3o mais \u00e1gil e eficiente. Neste encontro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5762,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,9],"tags":[],"class_list":["post-5761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Comunica\u00e7\u00e3o do Governo de MS Com foco no uso da tecnologia digital para o servi\u00e7o p\u00fablico, o governador Eduardo Riedel participou nesta quinta-feira (7) de uma reuni\u00e3o com a Meta, em S\u00e3o Paulo. O objetivo \u00e9 avaliar grandes oportunidades para tornar a gest\u00e3o estadual e o atendimento ao cidad\u00e3o mais \u00e1gil e eficiente. Neste encontro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-07T21:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"730\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\"},\"author\":{\"name\":\"Rose\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\"},\"headline\":\"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos\",\"datePublished\":\"2026-05-07T21:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg\",\"articleSection\":[\"Em destaque\",\"Pol\u00edtica\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\",\"name\":\"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg\",\"datePublished\":\"2026-05-07T21:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg\",\"width\":730,\"height\":480,\"caption\":\"Fotos: Bruno Chaves\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\",\"name\":\"Rose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"caption\":\"Rose\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/rose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/","og_locale":"pt_BR","og_type":"article","og_title":"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos - O PROGRESSO","og_description":"Comunica\u00e7\u00e3o do Governo de MS Com foco no uso da tecnologia digital para o servi\u00e7o p\u00fablico, o governador Eduardo Riedel participou nesta quinta-feira (7) de uma reuni\u00e3o com a Meta, em S\u00e3o Paulo. O objetivo \u00e9 avaliar grandes oportunidades para tornar a gest\u00e3o estadual e o atendimento ao cidad\u00e3o mais \u00e1gil e eficiente. Neste encontro [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-05-07T21:30:00+00:00","og_image":[{"width":730,"height":480,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg","type":"image\/jpeg"}],"author":"Rose","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rose","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/"},"author":{"name":"Rose","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b"},"headline":"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos","datePublished":"2026-05-07T21:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg","articleSection":["Em destaque","Pol\u00edtica"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/","name":"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg","datePublished":"2026-05-07T21:30:00+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/reuniao-META-Foto-Bruno-Chaves-04-730x480-1.jpeg","width":730,"height":480,"caption":"Fotos: Bruno Chaves"},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/07\/ms-debate-tecnologia-digital-para-modernizar-servicos-publicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"MS debate tecnologia digital para modernizar servi\u00e7os p\u00fablicos"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b","name":"Rose","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","caption":"Rose"},"url":"https:\/\/progresso.com.br\/index.php\/author\/rose\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5761"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5761\/revisions"}],"predecessor-version":[{"id":5763,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5761\/revisions\/5763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/5762"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}