{"id":6063,"date":"2026-05-11T10:41:23","date_gmt":"2026-05-11T14:41:23","guid":{"rendered":"https:\/\/progresso.com.br\/?p=6063"},"modified":"2026-05-11T10:41:23","modified_gmt":"2026-05-11T14:41:23","slug":"vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/","title":{"rendered":"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"454\" src=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg\" alt=\"\" class=\"wp-image-6065 size-full\" srcset=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg 567w, https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo-300x240.jpeg 300w, https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo-525x420.jpeg 525w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><em>Este pode at\u00e9 parecer um texto comercial, mas n\u00e3o \u00e9. Trata-se apenas de um texto informativo a respeito de um empreendimento que vai dar o que falar e que <strong>De Olho<\/strong> traz aqui alguns detalhes. A previs\u00e3o \u00e9 que o lan\u00e7amento oficial aconte\u00e7a em, no m\u00e1ximo, tr\u00eas meses. \u00c9 um shopping center, desses que a gente s\u00f3 v\u00ea em cidade grande. Anexo ao pr\u00e9dio principal ser\u00e3o erguidas duas torres: uma para abrigar um hotel e outra para atividades comerciais. E quem est\u00e1 \u00e0 frente garante: \u00e9 um shopping para atender Dourados e regi\u00e3o pelos pr\u00f3ximos 50 anos.<\/em><\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Shopping<\/strong><\/p>\n\n\n\n<p>Informa\u00e7\u00f5es apuradas pela coluna s\u00e3o claras: financeiramente, o empreendimento j\u00e1 est\u00e1 viabilizado, com pelos menos 70% dos investidores sendo de Dourados.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Shopping, ainda<\/strong><\/p>\n\n\n\n<p>De acordo com o projeto, inicialmente ser\u00e1 constru\u00eddo o pr\u00e9dio principal, com dois pisos, mas com alicerces j\u00e1 preparados para, nos pr\u00f3ximos anos (ou d\u00e9cadas), receber um terceiro piso.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Shopping, agora<\/strong><\/p>\n\n\n\n<p>Vamos nos a ter, portanto, ao que vem por a\u00ed, agora: vagas de estacionamento para 1,1 mil ve\u00edculos, com dois acessos por ruas diferentes.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Shopping, lojas<\/strong><\/p>\n\n\n\n<p>Nessa primeira fase, ser\u00e3o duas lojas \u00e2ncoras, um supermercado, 92 espa\u00e7os comerciais e uma academia. Tamb\u00e9m ter\u00e1 cinco salas de cinema.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Shopping, projeto<\/strong><\/p>\n\n\n\n<p>Conforme projeto apresentado para empreendedores, os espa\u00e7os amplos dar\u00e3o lugar a espelhos d\u00b4agua, paisagismo que inclui palmeiras e ventila\u00e7\u00e3o natural.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Escola<\/strong><\/p>\n\n\n\n<p>A deputada estadual Gleice Jane (PT) est\u00e1 organizando uma audi\u00eancia p\u00fablica com o tema \u00b4Escola perto de casa \u00e9 direito\u00b4. Ser\u00e1 na quinta-feira (14) desta semana, na sede do Sindracse, no Jardim Guaicurus, em Dourados.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Mais escola<\/strong><\/p>\n\n\n\n<p>A deputada avalia que n\u00e3o h\u00e1 escola suficiente para atender o grande n\u00famero de pessoas morando na regi\u00e3o do Jardim Guaicurus. Por isso, com a audi\u00eancia p\u00fablica, ela quer ouvir os moradores e, posteriormente, levar a demanda at\u00e9 o governo do Estado.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>M\u00e9dicos<\/strong><\/p>\n\n\n\n<p>Continua a saga para ter m\u00e9dicos capacitados no atendimento na UPA e no Hospital da Vida em Dourados. A correria est\u00e1 grande para manter os plant\u00f5es em pleno funcionamento.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>M\u00e9dicos, ainda<\/strong><\/p>\n\n\n\n<p>E como tudo nessa vida se resume no capitalismo, nessa \u00e1rea tamb\u00e9m \u00e9 assim. Para conseguir profissional disposto a ir a um dos dois locais, j\u00e1 est\u00e1 sendo oferecido at\u00e9 R$ 1.500,00 pelo per\u00edodo de um plant\u00e3o, para cobrir a \u00e1rea vermelha. Detalhe: pagamento \u00e0 vistinha, pelo Pix mesmo.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>M\u00e9dicos, acad\u00eamicos<\/strong><\/p>\n\n\n\n<p>Conforme passarinho piou \u00e0 coluna, acad\u00eamicos da UFGD (Universidade Federal da Grande Dourados) que cumprem est\u00e1gio est\u00e3o reclamando e, pior ainda, est\u00e3o temerosos com o que pode vir a acontecer. \u00b4Da n\u00e3o, tive que sair mais cedo pra n\u00e3o cometer nenhum crime\u00b4, escreveu um deles num grupo de whatsapp.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>M\u00e9dicos, relatos<\/strong><\/p>\n\n\n\n<p>No mesmo grupo, um outro relatou que uma m\u00e9dica que estava atendendo na \u00e1rea vermelha foi perguntar para outro m\u00e9dico \u00b4como rep\u00f5em pot\u00e1ssio\u00b4. E o tal tamb\u00e9m n\u00e3o sabia como fazer.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Mais relatos<\/strong><\/p>\n\n\n\n<p>Nesse caso do pot\u00e1ssio, \u00e9 a mesma m\u00e9dica que realizava atendimentos na \u00e1rea vermelha da UPA que estava fazendo sua estreia em plant\u00e3o de urg\u00eancia. Tudo sempre tem a primeira vez na vida, n\u00e9!<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>M\u00e9dicos, MP<\/strong><\/p>\n\n\n\n<p>Na semana passada, o grupo de m\u00e9dicos que trabalhava na UPA e no Hospital da Vida protocolou no Minist\u00e9rio P\u00fablico uma den\u00fancia enumerando os problemas.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Licen\u00e7a<\/strong><\/p>\n\n\n\n<p>Hoje, segunda-feira, 11 de maio, tem sess\u00e3o na C\u00e2mara Municipal de Dourados ainda sem a participa\u00e7\u00e3o da vereadora Isa Marcondes (Republicanos). Ela continua de licen\u00e7a m\u00e9dica, em fun\u00e7\u00e3o do procedimento de sa\u00fade a que se submeteu dias atr\u00e1s.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Licen\u00e7a, ainda<\/strong><\/p>\n\n\n\n<p>Seguindo o prazo do pedido de licen\u00e7a, a volta da vereadora \u00e0s atividades presenciais na C\u00e2mara est\u00e1 prevista para o a quinta-feira desta semana.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Com licen\u00e7a<\/strong><\/p>\n\n\n\n<p>Paralelamente, vai terminando o prazo para apresenta\u00e7\u00e3o do relat\u00f3rio final resultante da investiga\u00e7\u00e3o que est\u00e1 sendo feita ap\u00f3s a C\u00e2mara acatar den\u00fancia de que a vereadora fez uso indevido da verba de seu gabinete.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Press\u00e3o<\/strong><\/p>\n\n\n\n<p>Mesmo com todo tipo de press\u00e3o que anda rolando nos bastidores, tem vereador temendo seguir o caminho da cassa\u00e7\u00e3o do mandato da vereadora mais votada na atual legislatura em Dourados.<\/p>\n\n\n\n<p>&#8230;<\/p>\n\n\n\n<p><strong>Sem carimbo<\/strong><\/p>\n\n\n\n<p>Ali\u00e1s, a cassa\u00e7\u00e3o s\u00f3 n\u00e3o ficou carimbada mesmo diante do vazamento da movimenta\u00e7\u00e3o e pelo confronto entre dois coringas mand\u00f5es. Mas n\u00e3o se pode esquecer um ponto delicado nessa hist\u00f3ria: vai ter pr\u00eamio se Isa ficar ineleg\u00edvel. A conferir!<\/p>\n\n\n\n<p>&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este pode at\u00e9 parecer um texto comercial, mas n\u00e3o \u00e9. Trata-se apenas de um texto informativo a respeito de um empreendimento que vai dar o que falar e que De Olho traz aqui alguns detalhes. A previs\u00e3o \u00e9 que o lan\u00e7amento oficial aconte\u00e7a em, no m\u00e1ximo, tr\u00eas meses. \u00c9 um shopping center, desses que a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[26],"tags":[],"class_list":["post-6063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-de-olho"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Este pode at\u00e9 parecer um texto comercial, mas n\u00e3o \u00e9. Trata-se apenas de um texto informativo a respeito de um empreendimento que vai dar o que falar e que De Olho traz aqui alguns detalhes. A previs\u00e3o \u00e9 que o lan\u00e7amento oficial aconte\u00e7a em, no m\u00e1ximo, tr\u00eas meses. \u00c9 um shopping center, desses que a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-11T14:41:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"567\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alfredo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alfredo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\"},\"author\":{\"name\":\"Alfredo\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2\"},\"headline\":\"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos\",\"datePublished\":\"2026-05-11T14:41:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\"},\"wordCount\":789,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg\",\"articleSection\":[\"De Olho\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\",\"name\":\"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg\",\"datePublished\":\"2026-05-11T14:41:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg\",\"width\":567,\"height\":454},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2\",\"name\":\"Alfredo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g\",\"caption\":\"Alfredo\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/alfredo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos - O PROGRESSO","og_description":"Este pode at\u00e9 parecer um texto comercial, mas n\u00e3o \u00e9. Trata-se apenas de um texto informativo a respeito de um empreendimento que vai dar o que falar e que De Olho traz aqui alguns detalhes. A previs\u00e3o \u00e9 que o lan\u00e7amento oficial aconte\u00e7a em, no m\u00e1ximo, tr\u00eas meses. \u00c9 um shopping center, desses que a [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-05-11T14:41:23+00:00","og_image":[{"width":567,"height":454,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg","type":"image\/jpeg"}],"author":"Alfredo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Alfredo","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/"},"author":{"name":"Alfredo","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2"},"headline":"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos","datePublished":"2026-05-11T14:41:23+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/"},"wordCount":789,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg","articleSection":["De Olho"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/","name":"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg","datePublished":"2026-05-11T14:41:23+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/shopping-novo.jpeg","width":567,"height":454},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/11\/vem-ai-um-shopping-para-atender-dourados-pelos-proximos-50-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"Vem a\u00ed um shopping para atender Dourados pelos pr\u00f3ximos 50 anos"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/b7390ac97c5e156cc2e02aa8e88f1bf2","name":"Alfredo","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ca208a3111522ad69d765c6f0ea1ce4742c74e10aba78ae7158042d704d65a9f?s=96&d=mm&r=g","caption":"Alfredo"},"url":"https:\/\/progresso.com.br\/index.php\/author\/alfredo\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6063"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6063\/revisions"}],"predecessor-version":[{"id":6066,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6063\/revisions\/6066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/6065"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}