{"id":6315,"date":"2026-05-13T14:30:00","date_gmt":"2026-05-13T18:30:00","guid":{"rendered":"https:\/\/progresso.com.br\/?p=6315"},"modified":"2026-05-13T13:38:28","modified_gmt":"2026-05-13T17:38:28","slug":"projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente","status":"publish","type":"post","link":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/","title":{"rendered":"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente"},"content":{"rendered":"\n<p><em><strong>Reconhecimento foi conquistado na 3\u00aa edi\u00e7\u00e3o do Pr\u00eamio Educador Transformador, anunciada durante a Bett Brasil, em S\u00e3o Paulo (SP)<\/strong><\/em><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Uma iniciativa criada em Mato Grosso do Sul para reduzir desperd\u00edcios nas escolas e incentivar a sustentabilidade por meio da economia circular conquistou reconhecimento nacional. O projeto \u201cSIRE \u2013 Sistema de Reuso Escolar\u201d, idealizado pela educadora Daniele Bassanesi, de Navira\u00ed (MS), ficou em 3\u00ba lugar na categoria Jornada de Inclus\u00e3o e Sustentabilidade na Educa\u00e7\u00e3o, durante a 3\u00aa edi\u00e7\u00e3o do Pr\u00eamio Educador Transformador. A premia\u00e7\u00e3o foi anunciada no dia 6 de maio, em S\u00e3o Paulo (SP), durante a Bett Brasil \u2013 maior evento de inova\u00e7\u00e3o e tecnologia para a educa\u00e7\u00e3o da Am\u00e9rica Latina.<br><br>Promovido pelo Sebrae, Instituto Significare e Bett Brasil, o Pr\u00eamio Educador Transformador reconhece professores e gestores de institui\u00e7\u00f5es p\u00fablicas e privadas que desenvolvem solu\u00e7\u00f5es inovadoras para os desafios da educa\u00e7\u00e3o. Nesta edi\u00e7\u00e3o, o tema \u201cEduca\u00e7\u00e3o para enfrentar crises e construir futuros regenerativos\u201d incentivou projetos capazes de gerar impactos positivos e duradouros na forma\u00e7\u00e3o dos estudantes brasileiros.<br><br>Para a analista-t\u00e9cnica do Sebrae\/MS, Priscila Veloso, a conquista refor\u00e7a o protagonismo de Mato Grosso do Sul na promo\u00e7\u00e3o da educa\u00e7\u00e3o empreendedora e inovadora. \u201cProjetos como o SIRE mostram como a educa\u00e7\u00e3o pode unir inova\u00e7\u00e3o, sustentabilidade e protagonismo, ao possibilitar um melhor aproveitamento de materiais e recursos escolares com base na economia circular\u201d, destaca.<br><br>O SIRE foi desenvolvido para transformar a forma como as escolas administram seus recursos. Por meio da plataforma otimizadora, as institui\u00e7\u00f5es cadastram materiais que est\u00e3o sem uso, como itens produzidos para feiras, mostras cient\u00edficas, saraus e festas juninas, permitindo que outras escolas da rede possam solicitar, utilizar e posteriormente devolver os objetos \u00e0 unidade de origem. Com isso, o projeto amplia a vida \u00fatil dos materiais, reduz custos e desperd\u00edcios, incentivando pr\u00e1ticas sustent\u00e1veis dentro do ambiente escolar por meio de um ecossistema digital.<br>ideia surgiu a partir da experi\u00eancia profissional de Daniele Andressa Bassanesi em diferentes escolas e redes de ensino. Segundo ela, a aquisi\u00e7\u00e3o recorrente de materiais descart\u00e1veis para eventos escolares, somada ao desperd\u00edcio de recursos pouco tempo depois de serem utilizados, motivou a cria\u00e7\u00e3o do projeto SIRE junto \u00e0 gest\u00e3o da Escola Estadual Eurico Gaspar Dutra, em Navira\u00ed (MS).<br>Atualmente, Daniele atua como professora coordenadora de suporte \u00e0 aprendizagem na institui\u00e7\u00e3o, e afirma que o Sebrae teve papel importante em sua trajet\u00f3ria voltada \u00e0 inova\u00e7\u00e3o educacional. \u201cO Sebrae sempre foi um grande incentivador. Em 2013, participei do Desafio Universit\u00e1rio e fiquei em terceiro lugar estadual como professora orientadora. Foi quando me encantei ainda mais com o universo da inova\u00e7\u00e3o. Desde 2014, desenvolvo projetos e acumulo premia\u00e7\u00f5es locais ao longo dessa trajet\u00f3ria\u201d, relembra.<br>A educadora j\u00e1 havia conquistado o primeiro lugar na 2\u00aa edi\u00e7\u00e3o do Pr\u00eamio Educador Transformador, em 2024, na categoria Ensino M\u00e9dio. Agora, em 2026, retornou \u00e0 premia\u00e7\u00e3o com o projeto SIRE, desenvolvido especialmente para esta edi\u00e7\u00e3o.<br>Antes da implementa\u00e7\u00e3o da proposta, Daniele aplicou um question\u00e1rio em outras duas escolas, ouvindo 78 professores. O levantamento confirmou que o problema do desperd\u00edcio e da subutiliza\u00e7\u00e3o de recursos escolares \u00e9 recorrente, relevante e pass\u00edvel de amplia\u00e7\u00e3o em diferentes redes de ensino. \u201cA aceita\u00e7\u00e3o foi imediata e o di\u00e1logo com os parceiros aconteceu de forma muito natural, porque essa \u00e9 uma dor comum nas escolas. Acreditamos que, quando colocado em pr\u00e1tica, o projeto tamb\u00e9m contribuir\u00e1 para despertar nos estudantes a consci\u00eancia sobre sustentabilidade\u201d, explica.<br>Segundo a idealizadora, o SIRE nasceu com o prop\u00f3sito de integrar diferentes escolas e pode, futuramente, aproximar at\u00e9 mesmo redes de ensino distintas. Para ela, o reconhecimento estadual e nacional de um projeto ainda em fase de prototipagem representa uma grande conquista.<br>\u201cEstamos vivendo um momento de transi\u00e7\u00e3o na educa\u00e7\u00e3o, e ningu\u00e9m melhor do que n\u00f3s, educadores, para conduzir essa mudan\u00e7a. Inovar por meio de projetos \u00e9 uma forma de inspirar os estudantes a encontrarem solu\u00e7\u00f5es inteligentes para problemas sociais que impactam diretamente o cotidiano das escolas e da sociedade\u201d, afirma Bassanesi.<br>Na etapa nacional, os terceiros colocados de cada categoria receberam notebooks e mochilas como premia\u00e7\u00e3o.<br>Educa\u00e7\u00e3o Empreendedora<br>O Sebrae\/MS atua na divulga\u00e7\u00e3o e no incentivo \u00e0 participa\u00e7\u00e3o de profissionais atendidos pelo programa Educa\u00e7\u00e3o Empreendedora em iniciativas de inova\u00e7\u00e3o educacional. A proposta \u00e9 fortalecer a cultura empreendedora nas escolas e dar visibilidade a projetos que promovam transforma\u00e7\u00e3o social e desenvolvimento sustent\u00e1vel. Mais informa\u00e7\u00f5es podem ser obtidas pelo n\u00famero 0800 570 0800 ou pelo site\u00a0<a href=\"https:\/\/click.divulga.sebrae.ms\/?qs=ABB7InYiOjEsImQiOjQ4NzV9AAwAAAAAAJ0J-oBu6C_SawgA1BAobZUqad1KE81jwXS70Bm_BdPw6EtrEoPvRDZNfHZHW4ZwlwYf3EmKOZzr33lgey1I9WRpukvLAvtKmrsW\" target=\"_blank\" rel=\"noreferrer noopener\">ms.sebrae.com.br<\/a>.<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Reconhecimento foi conquistado na 3\u00aa edi\u00e7\u00e3o do Pr\u00eamio Educador Transformador, anunciada durante a Bett Brasil, em S\u00e3o Paulo (SP) Uma iniciativa criada em Mato Grosso do Sul para reduzir desperd\u00edcios nas escolas e incentivar a sustentabilidade por meio da economia circular conquistou reconhecimento nacional. O projeto \u201cSIRE \u2013 Sistema de Reuso Escolar\u201d, idealizado pela educadora [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6316,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,2],"tags":[],"class_list":["post-6315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-destaque"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente - O PROGRESSO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente - O PROGRESSO\" \/>\n<meta property=\"og:description\" content=\"Reconhecimento foi conquistado na 3\u00aa edi\u00e7\u00e3o do Pr\u00eamio Educador Transformador, anunciada durante a Bett Brasil, em S\u00e3o Paulo (SP) Uma iniciativa criada em Mato Grosso do Sul para reduzir desperd\u00edcios nas escolas e incentivar a sustentabilidade por meio da economia circular conquistou reconhecimento nacional. O projeto \u201cSIRE \u2013 Sistema de Reuso Escolar\u201d, idealizado pela educadora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\" \/>\n<meta property=\"og:site_name\" content=\"O PROGRESSO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T18:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rose\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rose\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\"},\"author\":{\"name\":\"Rose\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\"},\"headline\":\"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente\",\"datePublished\":\"2026-05-13T18:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\"},\"wordCount\":790,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg\",\"articleSection\":[\"Economia\",\"Em destaque\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\",\"url\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\",\"name\":\"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente - O PROGRESSO\",\"isPartOf\":{\"@id\":\"https:\/\/progresso.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg\",\"datePublished\":\"2026-05-13T18:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg\",\"width\":800,\"height\":534,\"caption\":\"A 3\u00aa edi\u00e7\u00e3o do pr\u00eamio contou com o tema \u201cEduca\u00e7\u00e3o para enfrentar crises e construir futuros regenerativos. Cr\u00e9dito imagem: Tulio Vidal\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/progresso.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/progresso.com.br\/#website\",\"url\":\"https:\/\/progresso.com.br\/\",\"name\":\"O PROGRESSO\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/progresso.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/progresso.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/progresso.com.br\/#organization\",\"name\":\"O PROGRESSO\",\"url\":\"https:\/\/progresso.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"contentUrl\":\"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg\",\"width\":1960,\"height\":1080,\"caption\":\"O PROGRESSO\"},\"image\":{\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/\",\"https:\/\/www.instagram.com\/oprogresso_digital\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b\",\"name\":\"Rose\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/progresso.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g\",\"caption\":\"Rose\"},\"url\":\"https:\/\/progresso.com.br\/index.php\/author\/rose\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente - O PROGRESSO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente - O PROGRESSO","og_description":"Reconhecimento foi conquistado na 3\u00aa edi\u00e7\u00e3o do Pr\u00eamio Educador Transformador, anunciada durante a Bett Brasil, em S\u00e3o Paulo (SP) Uma iniciativa criada em Mato Grosso do Sul para reduzir desperd\u00edcios nas escolas e incentivar a sustentabilidade por meio da economia circular conquistou reconhecimento nacional. O projeto \u201cSIRE \u2013 Sistema de Reuso Escolar\u201d, idealizado pela educadora [&hellip;]","og_url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/","og_site_name":"O PROGRESSO","article_publisher":"https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","article_published_time":"2026-05-13T18:30:00+00:00","og_image":[{"width":800,"height":534,"url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg","type":"image\/jpeg"}],"author":"Rose","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Rose","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#article","isPartOf":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/"},"author":{"name":"Rose","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b"},"headline":"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente","datePublished":"2026-05-13T18:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/"},"wordCount":790,"commentCount":0,"publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg","articleSection":["Economia","Em destaque"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/","url":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/","name":"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente - O PROGRESSO","isPartOf":{"@id":"https:\/\/progresso.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage"},"image":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage"},"thumbnailUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg","datePublished":"2026-05-13T18:30:00+00:00","breadcrumb":{"@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#primaryimage","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/05\/56b42d58-4629-4d1a-b551-adcdf6d6c04e.jpeg","width":800,"height":534,"caption":"A 3\u00aa edi\u00e7\u00e3o do pr\u00eamio contou com o tema \u201cEduca\u00e7\u00e3o para enfrentar crises e construir futuros regenerativos. Cr\u00e9dito imagem: Tulio Vidal"},{"@type":"BreadcrumbList","@id":"https:\/\/progresso.com.br\/index.php\/2026\/05\/13\/projeto-de-navirai-transforma-reaproveitamento-escolar-em-solucao-premiada-nacionalmente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/progresso.com.br\/"},{"@type":"ListItem","position":2,"name":"Projeto de Navira\u00ed transforma reaproveitamento escolar em solu\u00e7\u00e3o premiada nacionalmente"}]},{"@type":"WebSite","@id":"https:\/\/progresso.com.br\/#website","url":"https:\/\/progresso.com.br\/","name":"O PROGRESSO","description":"","publisher":{"@id":"https:\/\/progresso.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/progresso.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/progresso.com.br\/#organization","name":"O PROGRESSO","url":"https:\/\/progresso.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","contentUrl":"https:\/\/progresso.com.br\/wp-content\/uploads\/2026\/03\/logo_proog.jpg","width":1960,"height":1080,"caption":"O PROGRESSO"},"image":{"@id":"https:\/\/progresso.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1CeoksKBj6\/","https:\/\/www.instagram.com\/oprogresso_digital"]},{"@type":"Person","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/5dd27138d4463fbbaace62120bfc002b","name":"Rose","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/progresso.com.br\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1b6890e759cdd3a88d9f751cb423720b9861c5239167cd3586355638b6556599?s=96&d=mm&r=g","caption":"Rose"},"url":"https:\/\/progresso.com.br\/index.php\/author\/rose\/"}]}},"_links":{"self":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6315"}],"version-history":[{"count":1,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6315\/revisions"}],"predecessor-version":[{"id":6317,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6315\/revisions\/6317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media\/6316"}],"wp:attachment":[{"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/progresso.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}